{"id":1255,"date":"2023-01-18T16:41:58","date_gmt":"2023-01-18T15:41:58","guid":{"rendered":"https:\/\/www.multiserass.com\/il-gruppo\/"},"modified":"2024-03-22T11:21:31","modified_gmt":"2024-03-22T10:21:31","slug":"el-grupo","status":"publish","type":"page","link":"https:\/\/www.multiserass.com\/es\/el-grupo\/","title":{"rendered":"El Grupo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row padding_top_multiplier=\u00bb\u00bb padding_bottom_multiplier=\u00bb\u00bb][vc_column]<div class=\"grve-empty-space grve-tablet-sm-column-hide grve-mobile-column-hide\" style=\"height: 100px;\"><\/div><div class=\"grve-empty-space grve-desktop-column-hide grve-tablet-column-hide\" style=\"height: 50px;\"><\/div><div class=\"grve-element grve-image il-gruppo-icon-img grve-align-center\" style=\"\">  <div class=\"grve-image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"124\" height=\"124\" src=\"https:\/\/www.multiserass.com\/wp-content\/uploads\/2023\/11\/il_gruppo-icon.svg\" class=\"attachment-full size-full\" alt=\"\" \/>   <\/div><\/div><div class=\"grve-empty-space\" style=\"height: 30px;\"><\/div>[vc_column_text]<\/p>\n<h1 class=\"text_60_30 color_013A6F weight600 align_center\">EL GRUPO<\/h1>\n<p>[\/vc_column_text]<div class=\"grve-empty-space\" style=\"height: 10px;\"><\/div>[vc_column_text]<\/p>\n<p class=\"text_25_15 color_013A6F weight500 align_center line_height_1_1\">INNOVACI\u00d3N Y COMPETENCIAS ESPECIALIZADAS AL SERVICIO DE LA GESTI\u00d3N EXTERNALIZADA DE SINIESTROS<\/p>\n<p>[\/vc_column_text]<div class=\"grve-empty-space grve-tablet-sm-column-hide grve-mobile-column-hide\" style=\"height: 20px;\"><\/div><div class=\"grve-empty-space grve-desktop-column-hide grve-tablet-column-hide\" style=\"height: 10px;\"><\/div>[vc_column_text]<\/p>\n<p class=\"text_25_15 color_3B3B3B weight200 align_center line_height_1_1 gruppo-title-text\">El liderazgo en el mercado de MSA-Multi Serass se expande y fortalece gracias a su pertenencia al <span class=\"weight500 color_013A6F\">Grupo MSA Mizar<\/span> que, a trav\u00e9s de sus empresas, ofrece una respuesta cualificada en todas las fases de la gesti\u00f3n externalizada de siniestros.<\/p>\n<p>[\/vc_column_text]<div class=\"grve-empty-space\" style=\"height: 20px;\"><\/div>[vc_column_text]        <a href=\"https:\/\/www.msamizar.com\/\" target=\"_blank\">\n            <div class=\"section-scopri-btn es blu gruppo-mizar\">\n                <div class=\"back\">\n                <\/div>\n                <div class=\"arrow\">\n                                            <svg viewBox=\"0 0 14.854 11.188\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <g transform=\"matrix(-0.866025, 0.5, -0.5, -0.866025, 16.630354, 7.666324)\">\n                                <path d=\"M0,0,5.566,5.566,11.133,0\" transform=\"translate(5.566 0) rotate(90)\" fill=\"none\" stroke=\"#013a6f\" stroke-width=\"1\"><\/path>\n                                <path d=\"M0,0V15.27\" transform=\"translate(15.27 5.566) rotate(90)\" fill=\"none\" stroke=\"#013a6f\" stroke-width=\"1\"><\/path>\n                            <\/g>\n                        <\/svg>\n                    \n                <\/div>\n                <div class=\"text\">Visita el sitio web del Grupo<\/div>\n            <\/div>\n        <\/a>\n    [\/vc_column_text]<div class=\"grve-empty-space grve-tablet-sm-column-hide grve-mobile-column-hide\" style=\"height: 95px;\"><\/div><div class=\"grve-empty-space grve-desktop-column-hide grve-tablet-column-hide\" style=\"height: 50px;\"><\/div>[\/vc_column][\/vc_row][vc_row bg_type=\u00bbcolor\u00bb padding_top_multiplier=\u00bb\u00bb padding_bottom_multiplier=\u00bb\u00bb bg_color=\u00bb#ffffff\u00bb][vc_column][vc_column_text]        <div class=\"gruppo-societa desktop\">\n            <div class=\"owl-carousel\">\n                <div class=\"item\">\n                    <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_1.jpg\" srcset=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_1.jpg 1x, \/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_1@2x.jpg 2x\">\n                <\/div>\n                <div class=\"item\">\n                    <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_2.jpg\" srcset=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_2.jpg 1x, \/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_2@2x.jpg 2x\">\n                <\/div>\n                <div class=\"item\">\n                    <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_3.jpg\" srcset=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_3.jpg 1x, \/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_3@2x.jpg 2x\">\n                <\/div>\n                <div class=\"item\">\n                    <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_4.jpg\" srcset=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_4.jpg 1x, \/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_4@2x.jpg 2x\">\n                <\/div>\n                <div class=\"item\">\n                    <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_5.jpg\" srcset=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_5.jpg 1x, \/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_5@2x.jpg 2x\">\n                <\/div>\n                <div class=\"item\">\n                    <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_5.jpg\" srcset=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_6.jpg 1x, \/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_6@2x.jpg 2x\">\n                <\/div>\n            <\/div>\n\n            <div class=\"gruppo-societa-controls-text\">\n                <div class=\"gruppo-societa-controls\">\n                        <div class=\"carousel-controls left blue\">\n        <div class=\"left\">\n            <svg viewBox=\"0 0 30 28\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <line style=\"fill: white; stroke: white; stroke-width: 1px;\" x1=\"1.754\" y1=\"13.955\" x2=\"29.754\" y2=\"13.955\"><\/line>\n                <polyline style=\"fill: rgba(216, 216, 216, 0); stroke: white; stroke-width: 1px;\" points=\"14.759 1.078 1.77 13.994 14.707 26.946\"><\/polyline>\n            <\/svg>\n        <\/div>\n    <\/div>\n                        <div class=\"carousel-controls right blue\">\n        <div class=\"right\">\n            <svg viewBox=\"0 0 30 28\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <line style=\"fill: white; stroke: white; stroke-width: 1px;\" x1=\"1.754\" y1=\"13.955\" x2=\"29.754\" y2=\"13.955\"><\/line>\n                <polyline style=\"fill: rgba(216, 216, 216, 0); stroke: white; stroke-width: 1px;\" points=\"14.759 1.078 1.77 13.994 14.707 26.946\"><\/polyline>\n            <\/svg>\n        <\/div>\n    <\/div>\n                        <div class=\"carousel-index desktop\">\n        <p>\n            <span class='index index-2'>2<\/span><span class='index index-3'>3<\/span><span class='index index-4'>4<\/span><span class='index index-5'>5<\/span><span class='index index-6'>6<\/span><span class='index index-1'>1<\/span> \/6        <\/p>\n    <\/div>\n                <\/div>\n                <div class=\"gruppo-societa-text grve-mobile-column-hide\">\n                    <div rgb-copy-to=\"#gruppo-splide-desc-1\">\n                        <p class=\"text_45px color_2F6AF3 weight700 nomargin\">Accl\u00e0ims<\/p>\n                        <div class=\"grve-empty-space\" style=\"height: 10px;\"><\/div>\n                        <p class=\"text_25px line_height_1_2 color_5C5C5C weight500 nomargin\">Empresa especializada en la gesti\u00f3n de reclamaciones, servicios de back office (apertura de siniestros, devoluci\u00f3n de llamadas...) y auditor\u00eda t\u00e9cnica.<\/p>\n                    <\/div>\n                    <div rgb-copy-to=\"#gruppo-splide-desc-2\">\n                        <p class=\"text_45px color_AECD47 weight700 nomargin\">Network 4 Claims<\/p>\n                        <div class=\"grve-empty-space\" style=\"height: 10px;\"><\/div>\n                        <p class=\"text_25px line_height_1_2 color_5C5C5C weight500 nomargin\">Coordina una red cualificada de expertos y representantes externos (m\u00e9dicos, peritos, investigadores...). Se articula en torno a la centralizaci\u00f3n de procesos y utiliza una plataforma especializada de TI (Portal) que sistematiza los flujos de trabajo.<\/p>\n                    <\/div>\n                    <div rgb-copy-to=\"#gruppo-splide-desc-3\">\n                        <p class=\"text_45px color_433783 weight700 nomargin\">RipArte<\/p>\n                        <div class=\"grve-empty-space\" style=\"height: 10px;\"><\/div>\n                        <p class=\"text_25px line_height_1_2 color_5C5C5C weight500 nomargin\">Administra una amplia red de talleres de carrocer\u00eda concertados e interconectados a trav\u00e9s de un centro operativo y un software especializado propio (RiPortal), convirti\u00e9ndose en un socio estrat\u00e9gico al servicio de compa\u00f1\u00edas de seguros, flotas y talleres de carrocer\u00eda.<\/p>\n                    <\/div>\n                    <div rgb-copy-to=\"#gruppo-splide-desc-4\">\n                        <p class=\"text_45px color_0F5679 weight700 nomargin\">Dottor Grandine<\/p>\n                        <div class=\"grve-empty-space\" style=\"height: 10px;\"><\/div>\n                        <p class=\"text_25px line_height_1_2 color_5C5C5C weight500 nomargin\">Empresa especializada en servicios de reparaci\u00f3n de veh\u00edculos da\u00f1ados por granizo, a trav\u00e9s de una red integrada por m\u00e1s de 700 centros concertados.<\/p>\n                    <\/div>\n                    <div rgb-copy-to=\"#gruppo-splide-desc-5\">\n                        <p class=\"text_45px color_F8CD41 weight700 nomargin\">Legalade<\/p>\n                        <div class=\"grve-empty-space\" style=\"height: 10px;\"><\/div>\n                        <p class=\"text_25px line_height_1_2 color_5C5C5C weight500 nomargin\">Es un bufete de abogados. Gestiona litigios en materia de seguros en nombre de las compa\u00f1\u00edas. Utiliza un modelo innovador y centralizado; adem\u00e1s, ofrece cobertura en todo el territorio nacional.<\/p>\n                    <\/div>\n                    <div rgb-copy-to=\"#gruppo-splide-desc-6\">\n                        <p class=\"text_45px color_0337D7 weight700 nomargin\">Mizar Tech<\/p>\n                        <div class=\"grve-empty-space\" style=\"height: 10px;\"><\/div>\n                        <p class=\"text_25px line_height_1_2 color_5C5C5C weight500 nomargin\">Hub tecnol\u00f3gico del Grupo, desarrolla soluciones de TI avanzadas para prestar servicios altamente innovadores en el sector empresarial del Grupo y en otros mercados.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n        <div class=\"gruppo-societa mobile\">\n            <section class=\"splide\" aria-label=\"il gruppo\">\n                <ul class=\"splide__pagination\"><\/ul>\n\n                <div class=\"splide__track\">\n                    <ul class=\"splide__list\">\n                        <li class=\"splide__slide\">\n                            <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_mobile_1.jpg\">\n                            <div class=\"gruppo-splide-desc\" id=\"gruppo-splide-desc-1\"><\/div>\n                        <\/li>    \n                        <li class=\"splide__slide\">\n                            <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_mobile_2.jpg\">\n                            <div class=\"gruppo-splide-desc\" id=\"gruppo-splide-desc-2\"><\/div>\n                        <\/li>   \n                        <li class=\"splide__slide\">\n                            <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_mobile_3.jpg\">\n                            <div class=\"gruppo-splide-desc\" id=\"gruppo-splide-desc-3\"><\/div>\n                        <\/li>   \n                        <li class=\"splide__slide\">\n                            <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_mobile_4.jpg\">\n                            <div class=\"gruppo-splide-desc\" id=\"gruppo-splide-desc-4\"><\/div>\n                        <\/li>   \n                        <li class=\"splide__slide\">\n                            <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_mobile_5.jpg\">\n                            <div class=\"gruppo-splide-desc\" id=\"gruppo-splide-desc-5\"><\/div>\n                        <\/li>   \n                        <li class=\"splide__slide\">\n                            <img decoding=\"async\" src=\"\/wp-content\/themes\/movedo-child\/assets_multiserass\/gruppo_societa_mobile_6.jpg\">\n                            <div class=\"gruppo-splide-desc\" id=\"gruppo-splide-desc-6\"><\/div>\n                        <\/li>                       \n                    <\/ul>\n                <\/div>\n            <\/section>\n        <\/div>\n    [\/vc_column_text][\/vc_column][\/vc_row][vc_row bg_type=\u00bbcolor\u00bb padding_top_multiplier=\u00bb\u00bb padding_bottom_multiplier=\u00bb\u00bb bg_color=\u00bb#ffffff\u00bb][vc_column]<div class=\"grve-empty-space grve-tablet-sm-column-hide grve-mobile-column-hide\" style=\"height: 150px;\"><\/div><div class=\"grve-empty-space grve-desktop-column-hide grve-tablet-column-hide\" style=\"height: 70px;\"><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row padding_top_multiplier=\u00bb\u00bb padding_bottom_multiplier=\u00bb\u00bb][vc_column][vc_column_text] EL GRUPO [\/vc_column_text][vc_column_text] INNOVACI\u00d3N Y COMPETENCIAS ESPECIALIZADAS AL SERVICIO DE LA GESTI\u00d3N EXTERNALIZADA DE SINIESTROS [\/vc_column_text][vc_column_text] El liderazgo en el mercado de MSA-Multi Serass se expande y fortalece gracias a su pertenencia al Grupo MSA Mizar que, a trav\u00e9s de sus empresas, ofrece una respuesta cualificada en todas las fases de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-1255","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Grupo - Multiserass<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.multiserass.com\/es\/el-grupo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Grupo - Multiserass\" \/>\n<meta property=\"og:description\" content=\"[vc_row padding_top_multiplier=\u00bb\u00bb padding_bottom_multiplier=\u00bb\u00bb][vc_column][vc_column_text] EL GRUPO [\/vc_column_text][vc_column_text] INNOVACI\u00d3N Y COMPETENCIAS ESPECIALIZADAS AL SERVICIO DE LA GESTI\u00d3N EXTERNALIZADA DE SINIESTROS [\/vc_column_text][vc_column_text] El liderazgo en el mercado de MSA-Multi Serass se expande y fortalece gracias a su pertenencia al Grupo MSA Mizar que, a trav\u00e9s de sus empresas, ofrece una respuesta cualificada en todas las fases de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.multiserass.com\/es\/el-grupo\/\" \/>\n<meta property=\"og:site_name\" content=\"Multiserass\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-22T10:21:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.multiserass.com\\\/es\\\/el-grupo\\\/\",\"url\":\"https:\\\/\\\/www.multiserass.com\\\/es\\\/el-grupo\\\/\",\"name\":\"El Grupo - Multiserass\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.multiserass.com\\\/es\\\/#website\"},\"datePublished\":\"2023-01-18T15:41:58+00:00\",\"dateModified\":\"2024-03-22T10:21:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.multiserass.com\\\/es\\\/el-grupo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.multiserass.com\\\/es\\\/el-grupo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.multiserass.com\\\/es\\\/el-grupo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.multiserass.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Grupo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.multiserass.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.multiserass.com\\\/es\\\/\",\"name\":\"Multiserass\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.multiserass.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Grupo - Multiserass","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.multiserass.com\/es\/el-grupo\/","og_locale":"es_ES","og_type":"article","og_title":"El Grupo - Multiserass","og_description":"[vc_row padding_top_multiplier=\u00bb\u00bb padding_bottom_multiplier=\u00bb\u00bb][vc_column][vc_column_text] EL GRUPO [\/vc_column_text][vc_column_text] INNOVACI\u00d3N Y COMPETENCIAS ESPECIALIZADAS AL SERVICIO DE LA GESTI\u00d3N EXTERNALIZADA DE SINIESTROS [\/vc_column_text][vc_column_text] El liderazgo en el mercado de MSA-Multi Serass se expande y fortalece gracias a su pertenencia al Grupo MSA Mizar que, a trav\u00e9s de sus empresas, ofrece una respuesta cualificada en todas las fases de la [&hellip;]","og_url":"https:\/\/www.multiserass.com\/es\/el-grupo\/","og_site_name":"Multiserass","article_modified_time":"2024-03-22T10:21:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.multiserass.com\/es\/el-grupo\/","url":"https:\/\/www.multiserass.com\/es\/el-grupo\/","name":"El Grupo - Multiserass","isPartOf":{"@id":"https:\/\/www.multiserass.com\/es\/#website"},"datePublished":"2023-01-18T15:41:58+00:00","dateModified":"2024-03-22T10:21:31+00:00","breadcrumb":{"@id":"https:\/\/www.multiserass.com\/es\/el-grupo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.multiserass.com\/es\/el-grupo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.multiserass.com\/es\/el-grupo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.multiserass.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Grupo"}]},{"@type":"WebSite","@id":"https:\/\/www.multiserass.com\/es\/#website","url":"https:\/\/www.multiserass.com\/es\/","name":"Multiserass","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.multiserass.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.multiserass.com\/es\/wp-json\/wp\/v2\/pages\/1255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.multiserass.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.multiserass.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.multiserass.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.multiserass.com\/es\/wp-json\/wp\/v2\/comments?post=1255"}],"version-history":[{"count":3,"href":"https:\/\/www.multiserass.com\/es\/wp-json\/wp\/v2\/pages\/1255\/revisions"}],"predecessor-version":[{"id":1396,"href":"https:\/\/www.multiserass.com\/es\/wp-json\/wp\/v2\/pages\/1255\/revisions\/1396"}],"wp:attachment":[{"href":"https:\/\/www.multiserass.com\/es\/wp-json\/wp\/v2\/media?parent=1255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}